{"id":3939,"date":"2022-10-07T04:20:31","date_gmt":"2022-10-07T04:20:31","guid":{"rendered":"https:\/\/expocobre.com\/?page_id=3939"},"modified":"2026-04-28T16:07:01","modified_gmt":"2026-04-28T21:07:01","slug":"tipos-entradas","status":"publish","type":"page","link":"https:\/\/expocobre.com\/en\/tipos-entradas\/","title":{"rendered":"Types of Tickets"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"3939\" class=\"elementor elementor-3939\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-98afc91 e-con-full e-flex e-con e-parent\" data-id=\"98afc91\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-575133d elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"575133d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">TIPOS DE <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9233061 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"9233061\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ENTRADA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9d6fe34 e-flex e-con-boxed e-con e-parent\" data-id=\"9d6fe34\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-442f357 e-con-full e-flex e-con e-child\" data-id=\"442f357\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f8be1f2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f8be1f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fcb9930 elementor-widget elementor-widget-heading\" data-id=\"fcb9930\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><b>S\u00c9 PARTE DE ESTE IMPORTANTE\nEVENTO<\/b><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9701253 elementor-widget elementor-widget-heading\" data-id=\"9701253\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">In <b>EXPOCOBRE 2026<\/b> hemos dise\u00f1ado dos modalidades de ingreso para que vivas la experiencia a tu manera. Ya sea explorando la feria minera o participando activamente en las conferencias internacionales, \u00a1t\u00fa eliges c\u00f3mo ser parte del evento minero m\u00e1s importante de la regi\u00f3n!<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5a6e2dd e-con-full e-flex e-con e-child\" data-id=\"5a6e2dd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6f62f30 elementor-widget elementor-widget-html\" data-id=\"6f62f30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<!DOCTYPE html>\n<html lang=\"es\">\n<head>\n    <meta charset=\"UTF-8\">\n    <meta name=\"viewport\" content=\"width=device-width, initial-scale=1.0\">\n    <title>Programa de Eventos<\/title>\n    <style>\n        :root {\n            --color-marron-evento: #a65e33;\n            --fuente-evento: 'Segoe UI', Tahoma, Geneva, Verdana, sans-serif;\n        }\n\n        \/* Contenedor principal para no mover el resto de tu web *\/\n        .seccion-botones-programa {\n            display: flex;\n            justify-content: center;\n            flex-wrap: wrap; \n            gap: 20px;\n            padding: 0px 10px;\n            width: 100%;\n            box-sizing: border-box;\n            background-color: transparent;\n        }\n\n        .tarjeta-boton-ev {\n            background-color: white;\n            border-radius: 20px;\n            width: 320px;\n            box-shadow: 0 4px 12px rgba(0,0,0,0.1);\n            overflow: hidden;\n            border: 1px solid #e0e0e0;\n            display: flex;\n            flex-direction: column;\n            transition: transform 0.2s ease;\n        }\n\n        .tarjeta-boton-ev:hover {\n            transform: translateY(-3px);\n            box-shadow: 0 6px 18px rgba(0,0,0,0.15);\n        }\n\n        .franja-top-ev {\n            background-color: var(--color-marron-evento);\n            color: white;\n            padding: 10px;\n            text-align: center;\n            font-size: 11px;\n            font-weight: bold;\n            text-transform: uppercase;\n            margin: 5px 5px 0 5px;\n            border-radius: 12px 12px 0 0;\n        }\n\n        .cuerpo-boton-ev {\n            padding: 35px 15px;\n            text-align: center;\n        }\n\n        .cuerpo-boton-ev h2 {\n            margin: 0;\n            color: #444;\n            font-size: 1.1rem;\n            font-family: var(--fuente-evento);\n            text-transform: uppercase;\n            margin-bottom: 10px;\n        }\n\n        .link-descarga {\n            display: inline-block;\n            font-size: 0.9rem;\n            color: var(--color-marron-evento);\n            text-decoration: underline;\n            font-weight: bold;\n            cursor: pointer;\n            border: none;\n            background: none;\n            padding: 5px;\n        }\n\n        \/* --- ESTILOS DEL POP-UP (MODAL) --- *\/\n        .modal-overlay {\n            display: none;\n            position: fixed;\n            top: 0;\n            left: 0;\n            width: 100%;\n            height: 100%;\n            background-color: rgba(0, 0, 0, 0.7);\n            z-index: 9999;\n            justify-content: center;\n            align-items: center;\n            opacity: 0;\n            transition: opacity 0.3s ease;\n        }\n\n        .modal-overlay.active {\n            display: flex;\n            opacity: 1;\n        }\n\n        .modal-content {\n            background-color: white;\n            padding: 30px;\n            border-radius: 20px;\n            width: 90%;\n            max-width: 500px;\n            text-align: center;\n            position: relative;\n            transform: scale(0.9);\n            transition: transform 0.3s ease;\n        }\n\n        .modal-overlay.active .modal-content {\n            transform: scale(1);\n        }\n\n        .modal-close {\n            position: absolute;\n            top: 15px;\n            right: 15px;\n            font-size: 24px;\n            color: #888;\n            cursor: pointer;\n            line-height: 1;\n        }\n\n        .modal-body {\n            display: flex;\n            flex-direction: column;\n            gap: 12px;\n            margin-top: 20px;\n        }\n\n        .btn-forum-link {\n            background-color: white;\n            color: var(--color-marron-evento);\n            border: 2px solid var(--color-marron-evento);\n            padding: 12px 15px;\n            border-radius: 10px;\n            font-size: 0.85rem;\n            font-weight: bold;\n            text-decoration: none;\n            text-transform: uppercase;\n            transition: all 0.2s ease;\n        }\n\n        .btn-forum-link:hover {\n            background-color: var(--color-marron-evento);\n            color: white;\n        }\n\n        @media (max-width: 680px) {\n            .seccion-botones-programa { flex-direction: column; align-items: center; }\n        }\n    <\/style>\n<\/head>\n<body>\n\n<div class=\"seccion-botones-programa\">\n    \n    <div class=\"tarjeta-boton-ev\">\n        <div class=\"franja-top-ev\">INGRESO CON ENTRADA VIP<\/div>\n        <div class=\"cuerpo-boton-ev\">\n            <h2>PROGRAMA AUDITORIO PRINCIPAL<\/h2>\n            <a href=\"https:\/\/drive.google.com\/file\/d\/1m6lNK0Ro_OCoa3-QdfDo6pxpQrvo9U9c\/view?usp=sharing\" \n               target=\"_blank\" \n               class=\"link-descarga\">\n               DOWNLOAD PROGRAM\n            <\/a>\n        <\/div>\n    <\/div>\n\n    <div class=\"tarjeta-boton-ev\">\n        <div class=\"franja-top-ev\">INGRESO CON PASE VISITANTE T\u00c9CNICO<\/div>\n        <div class=\"cuerpo-boton-ev\">\n            <h2>PROGRAMA FOROS T\u00c9CNICOS<\/h2>\n            <span id=\"btnOpenForos\" class=\"link-descarga\">DOWNLOAD PROGRAM<\/span>\n        <\/div>\n    <\/div>\n\n<\/div>\n\n<div class=\"modal-overlay\" id=\"modalForos\">\n    <div class=\"modal-content\">\n        <span class=\"modal-close\" id=\"btnCloseForos\">&times;<\/span>\n        <h3 style=\"color:#444; font-family: sans-serif; margin-bottom: 20px;\">SELECCIONE UN PROGRAMA<\/h3>\n        <div class=\"modal-body\">\n            <a href=\"https:\/\/drive.google.com\/file\/d\/11vvgtz4i9up79ASzkdQaelgGaOBsbeVh\/view?usp=sharing\" target=\"_blank\" class=\"btn-forum-link\">FORO DE INNOVACI\u00d3N TECNOL\u00d3GICA EN COBRE<\/a>\n            <a href=\"https:\/\/drive.google.com\/file\/d\/1FtW9NDCI__cxNRq2OATewTOkdDh717PD\/view?usp=sharing\" target=\"_blank\" class=\"btn-forum-link\">FORO DE INVESTIGACI\u00d3N MINERA UNIVERSITARIA<\/a>\n            <a href=\"https:\/\/drive.google.com\/file\/d\/1iF5Ptr7oiuIaXwt99atYewttkDzaoNKe\/view?usp=sharing\" target=\"_blank\" class=\"btn-forum-link\">FORO DE MANTENIMIENTO<\/a>\n            <a href=\"https:\/\/drive.google.com\/file\/d\/1Vx_kxOH0ngj0Dybsks1IjXaNWq46p3EA\/view?usp=sharing\" target=\"_blank\" class=\"btn-forum-link\">FORO DE PROYECTOS DEL COBRE<\/a>\n        <\/div>\n    <\/div>\n<\/div>\n\n<script>\n    const modal = document.getElementById('modalForos');\n    const btnOpen = document.getElementById('btnOpenForos');\n    const btnClose = document.getElementById('btnCloseForos');\n\n    btnOpen.onclick = () => modal.classList.add('active');\n    btnClose.onclick = () => modal.classList.remove('active');\n    \n    window.onclick = (event) => {\n        if (event.target == modal) modal.classList.remove('active');\n    }\n<\/script>\n\n<\/body>\n<\/html>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4fce85c e-flex e-con-boxed e-con e-parent\" data-id=\"4fce85c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c132c79 elementor-widget elementor-widget-heading\" data-id=\"c132c79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><b>conoce los beneficios adicionales con tu entrada vip<img decoding=\"async\" role=\"img\" class=\"emoji lazyload\" alt=\"\u2b07\ufe0f\" data-src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/2b07.svg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\"><\/b><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc6bd0b elementor-widget elementor-widget-heading\" data-id=\"cc6bd0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Una experiencia dise\u00f1ada para quienes buscan informaci\u00f3n de alto nivel, <br><b>certificaci\u00f3n <\/b>acad\u00e9mica y <b>conexiones <\/b>clave.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-895c714 e-flex e-con-boxed e-con e-parent\" data-id=\"895c714\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-efd300c e-con-full e-flex e-con e-child\" data-id=\"efd300c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f807773 elementor-widget elementor-widget-spacer\" data-id=\"f807773\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-367c8cf elementor-widget elementor-widget-heading\" data-id=\"367c8cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><b>VIP<\/b><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b5fdf54 elementor-widget elementor-widget-heading\" data-id=\"b5fdf54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><b>PASE CON ACCESO COMPLETO<\/b><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c97ef01 elementor-widget elementor-widget-heading\" data-id=\"c97ef01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><b>INVERSI\u00d3N: USD 420 <\/b><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3acda30 elementor-widget elementor-widget-heading\" data-id=\"3acda30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">incluye impuestos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49edb99 elementor-widget elementor-widget-image\" data-id=\"49edb99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"615\" height=\"653\" src=\"https:\/\/expocobre.com\/wp-content\/uploads\/2026\/04\/INSCRIPCIONES-EXPOCOBRE-2026.png\" class=\"attachment-large size-large wp-image-63427\" alt=\"\" srcset=\"https:\/\/expocobre.com\/wp-content\/uploads\/2026\/04\/INSCRIPCIONES-EXPOCOBRE-2026.png 615w, https:\/\/expocobre.com\/wp-content\/uploads\/2026\/04\/INSCRIPCIONES-EXPOCOBRE-2026-283x300.png 283w, https:\/\/expocobre.com\/wp-content\/uploads\/2026\/04\/INSCRIPCIONES-EXPOCOBRE-2026-11x12.png 11w\" sizes=\"(max-width: 615px) 100vw, 615px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4a075a elementor-align-left elementor-widget elementor-widget-button\" data-id=\"c4a075a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/forms.gle\/cQzHVZSLdWbk13bo9\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-alt-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zM140 300h116v70.9c0 10.7 13 16.1 20.5 8.5l114.3-114.9c4.7-4.7 4.7-12.2 0-16.9l-114.3-115c-7.6-7.6-20.5-2.2-20.5 8.5V212H140c-6.6 0-12 5.4-12 12v64c0 6.6 5.4 12 12 12z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">JOIN NOW<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1221c0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a1221c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5d76a0 elementor-widget elementor-widget-spacer\" data-id=\"e5d76a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-090ba5d e-con-full e-flex e-con e-child\" data-id=\"090ba5d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-54a20b5 elementor-widget elementor-widget-image\" data-id=\"54a20b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"508\" height=\"704\" data-src=\"https:\/\/expocobre.com\/wp-content\/uploads\/2025\/09\/FOTO-VIP-2.png\" class=\"attachment-large size-large wp-image-23044 lazyload\" alt=\"\" data-srcset=\"https:\/\/expocobre.com\/wp-content\/uploads\/2025\/09\/FOTO-VIP-2.png 508w, https:\/\/expocobre.com\/wp-content\/uploads\/2025\/09\/FOTO-VIP-2-216x300.png 216w, https:\/\/expocobre.com\/wp-content\/uploads\/2025\/09\/FOTO-VIP-2-9x12.png 9w\" data-sizes=\"(max-width: 508px) 100vw, 508px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 508px; --smush-placeholder-aspect-ratio: 508\/704;\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e94a7d3 e-flex e-con-boxed e-con e-parent\" data-id=\"e94a7d3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-da36f65 e-con-full e-flex e-con e-child\" data-id=\"da36f65\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e8f2a2f elementor-widget elementor-widget-spacer\" data-id=\"e8f2a2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16327d1 elementor-widget elementor-widget-heading\" data-id=\"16327d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><b>TECHNICAL VISITOR<\/b><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8e8d2f elementor-widget elementor-widget-heading\" data-id=\"a8e8d2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><b>PASE GENERAL GRATUITO<\/b>\n<br>Dirigido exclusivamente al sector minero<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-975329b elementor-widget elementor-widget-heading\" data-id=\"975329b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Disfruta de la Feria Minera Internacional <b>sin costo<\/b>. <br>Conecta con empresas, visita stands y descubre lo \u00faltimo en innovaci\u00f3n y servicios para la industria minera.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52fd8e1 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"52fd8e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"609\" height=\"163\" data-src=\"https:\/\/expocobre.com\/wp-content\/uploads\/2025\/09\/GRATIS-PASE.png\" class=\"attachment-large size-large wp-image-22947 lazyload\" alt=\"\" data-srcset=\"https:\/\/expocobre.com\/wp-content\/uploads\/2025\/09\/GRATIS-PASE.png 609w, https:\/\/expocobre.com\/wp-content\/uploads\/2025\/09\/GRATIS-PASE-300x80.png 300w, https:\/\/expocobre.com\/wp-content\/uploads\/2025\/09\/GRATIS-PASE-18x5.png 18w\" data-sizes=\"(max-width: 609px) 100vw, 609px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 609px; --smush-placeholder-aspect-ratio: 609\/163;\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-031efed elementor-widget elementor-widget-text-editor\" data-id=\"031efed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><b>IMPORTANTE<\/b>: Solo necesitas completar el registro para recibir tu entrada digital. RECUERDA REVISAR SPAM \/ BUZ\u00d3N DE CORREOS NO DESEADOS.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5791bb9 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5791bb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ba03c7 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"9ba03c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/expocobre.com\/en\/tipos-entradas\/visitante-tecnico\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-alt-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zM140 300h116v70.9c0 10.7 13 16.1 20.5 8.5l114.3-114.9c4.7-4.7 4.7-12.2 0-16.9l-114.3-115c-7.6-7.6-20.5-2.2-20.5 8.5V212H140c-6.6 0-12 5.4-12 12v64c0 6.6 5.4 12 12 12z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">REG\u00cdSTRATE GRATIS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-175f344 e-con-full e-flex e-con e-child\" data-id=\"175f344\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b0db27 elementor-widget elementor-widget-image\" data-id=\"4b0db27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"508\" height=\"704\" data-src=\"https:\/\/expocobre.com\/wp-content\/uploads\/2025\/09\/libre.png\" class=\"attachment-large size-large wp-image-23000 lazyload\" alt=\"\" data-srcset=\"https:\/\/expocobre.com\/wp-content\/uploads\/2025\/09\/libre.png 508w, https:\/\/expocobre.com\/wp-content\/uploads\/2025\/09\/libre-216x300.png 216w, https:\/\/expocobre.com\/wp-content\/uploads\/2025\/09\/libre-9x12.png 9w\" data-sizes=\"(max-width: 508px) 100vw, 508px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 508px; --smush-placeholder-aspect-ratio: 508\/704;\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d97feff e-flex e-con-boxed e-con e-parent\" data-id=\"d97feff\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-95ff8bf elementor-widget elementor-widget-heading\" data-id=\"95ff8bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><b>\u00bfQu\u00e9 incluye cada entrada? <\/b>\n<br>Desc\u00fabrelo aqu\u00ed\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d8de831 e-flex e-con-boxed e-con e-parent\" data-id=\"d8de831\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-17acf35 e-con-full e-flex e-con e-child\" data-id=\"17acf35\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-731d189 elementor-widget elementor-widget-heading\" data-id=\"731d189\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><b>\u00bfCu\u00e1l eliges?<\/b><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ef11e8c e-con-full e-flex e-con e-child\" data-id=\"ef11e8c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-66bf9bb elementor-widget elementor-widget-button\" data-id=\"66bf9bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/expocobre.com\/en\/tipos-entradas\/visitante-tecnico\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">REGISTRO GRATUITO<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-94ee3f7 e-con-full e-flex e-con e-child\" data-id=\"94ee3f7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cb2ff14 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"cb2ff14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/expocobre.com\/en\/tipos-entradas\/vip\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">QUIERO EL PASE VIP<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f275c39 e-flex e-con-boxed e-con e-parent\" data-id=\"f275c39\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8c0eb68 elementor-widget elementor-widget-html\" data-id=\"8c0eb68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<div style=\"overflow-x:auto; margin:40px 0;\">\r\n<table style=\"width:100%; border-collapse: collapse; font-family: Arial, sans-serif; text-align:center;\">\r\n<thead>\r\n<tr style=\"background-color:#8B4513; color:white;\">\r\n<th style=\"padding:20px;\">Beneficios<\/th>\r\n<th style=\"padding:15px;\">Visitante T\u00e9cnico<br><big>(Gratis)<\/small><\/th>\r\n<th style=\"padding:15px; background-color:#f4b400; color:black;\">Pase VIP<\/th>\r\n<\/tr>\r\n<\/thead>\r\n<tbody>\r\n<tr>\r\n<td style=\"padding:12px; border:1px solid #ddd;\">Acceso a Feria Minera<\/td>\r\n<td style=\"border:1px solid #ddd;\">\u2714<\/td>\r\n<td style=\"border:1px solid #ddd;\">\u2714<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"padding:12px; border:1px solid #ddd;\">04 Foros T\u00e9cnicos<\/td>\r\n<td style=\"border:1px solid #ddd;\">\u2714<\/td>\r\n<td style=\"border:1px solid #ddd;\">\u2714<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"padding:12px; border:1px solid #ddd;\">Keynote Lectures<\/td>\r\n<td style=\"border:1px solid #ddd;\">\u2014<\/td>\r\n<td style=\"border:1px solid #ddd;\">\u2714<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"padding:12px; border:1px solid #ddd;\">Paneles Internacionales<\/td>\r\n<td style=\"border:1px solid #ddd;\">\u2014<\/td>\r\n<td style=\"border:1px solid #ddd;\">\u2714<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"padding:12px; border:1px solid #ddd;\">02 C\u00f3ctel Networking<\/td>\r\n<td style=\"border:1px solid #ddd;\">\u2014<\/td>\r\n<td style=\"border:1px solid #ddd;\">\u2714<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"padding:12px; border:1px solid #ddd;\">Certificado Digital<\/td>\r\n<td style=\"border:1px solid #ddd;\">\u2014<\/td>\r\n<td style=\"border:1px solid #ddd;\">\u2714<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-03f67a9 e-flex e-con-boxed e-con e-parent\" data-id=\"03f67a9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1b45cf3 e-con-full e-flex e-con e-child\" data-id=\"1b45cf3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-715dd5c elementor-widget elementor-widget-spacer\" data-id=\"715dd5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c7f6a8 elementor-widget elementor-widget-heading\" data-id=\"5c7f6a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><b>COMUN\u00cdCATE CON NUESTRO EQUIPO<\/b><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b08ed9 elementor-widget elementor-widget-spacer\" data-id=\"6b08ed9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4ac2107 e-con-full e-flex e-con e-child\" data-id=\"4ac2107\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1180031 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"1180031\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/wa.link\/yrnvyn\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-whatsapp\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M380.9 97.1C339 55.1 283.2 32 223.9 32c-122.4 0-222 99.6-222 222 0 39.1 10.2 77.3 29.6 111L0 480l117.7-30.9c32.4 17.7 68.9 27 106.1 27h.1c122.3 0 224.1-99.6 224.1-222 0-59.3-25.2-115-67.1-157zm-157 341.6c-33.2 0-65.7-8.9-94-25.7l-6.7-4-69.8 18.3L72 359.2l-4.4-7c-18.5-29.4-28.2-63.3-28.2-98.2 0-101.7 82.8-184.5 184.6-184.5 49.3 0 95.6 19.2 130.4 54.1 34.8 34.9 56.2 81.2 56.1 130.5 0 101.8-84.9 184.6-186.6 184.6zm101.2-138.2c-5.5-2.8-32.8-16.2-37.9-18-5.1-1.9-8.8-2.8-12.5 2.8-3.7 5.6-14.3 18-17.6 21.8-3.2 3.7-6.5 4.2-12 1.4-32.6-16.3-54-29.1-75.5-66-5.7-9.8 5.7-9.1 16.3-30.3 1.8-3.7.9-6.9-.5-9.7-1.4-2.8-12.5-30.1-17.1-41.2-4.5-10.8-9.1-9.3-12.5-9.5-3.2-.2-6.9-.2-10.6-.2-3.7 0-9.7 1.4-14.8 6.9-5.1 5.6-19.4 19-19.4 46.3 0 27.3 19.9 53.7 22.6 57.4 2.8 3.7 39.1 59.7 94.8 83.8 35.2 15.2 49 16.5 66.6 13.9 10.7-1.6 32.8-13.4 37.4-26.4 4.6-13 4.6-24.1 3.2-26.4-1.3-2.5-5-3.9-10.5-6.6z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">+51 960 995 971<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2887323 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"2887323\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/INSCRIPCIONES@EXPOCOBRE.COM\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">INSCRIPCIONES@EXPOCOBRE.COM<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>TIPOS DE ENTRADA S\u00c9 PARTE DE ESTE IMPORTANTE EVENTO En EXPOCOBRE 2026 hemos dise\u00f1ado dos modalidades de ingreso para que vivas la experiencia a tu manera. Ya sea explorando la feria minera o participando activamente en las conferencias internacionales, \u00a1t\u00fa eliges c\u00f3mo ser parte del evento minero m\u00e1s importante de la regi\u00f3n! Programa de Eventos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3939","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/expocobre.com\/en\/wp-json\/wp\/v2\/pages\/3939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expocobre.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/expocobre.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/expocobre.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/expocobre.com\/en\/wp-json\/wp\/v2\/comments?post=3939"}],"version-history":[{"count":150,"href":"https:\/\/expocobre.com\/en\/wp-json\/wp\/v2\/pages\/3939\/revisions"}],"predecessor-version":[{"id":64074,"href":"https:\/\/expocobre.com\/en\/wp-json\/wp\/v2\/pages\/3939\/revisions\/64074"}],"wp:attachment":[{"href":"https:\/\/expocobre.com\/en\/wp-json\/wp\/v2\/media?parent=3939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}